{"id":822,"count":4,"description":"","link":"https:\/\/lamaletadelili.com\/ca\/tag\/bruno-munari\/","name":"Bruno Munari","slug":"bruno-munari","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bruno Munari archivos - La maleta de Lili<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lamaletadelili.com\/ca\/tag\/bruno-munari\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bruno Munari archivos - La maleta de Lili\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lamaletadelili.com\/ca\/tag\/bruno-munari\/\" \/>\n<meta property=\"og:site_name\" content=\"La maleta de Lili\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/lamaletadelili.com\\\/ca\\\/tag\\\/bruno-munari\\\/\",\"url\":\"https:\\\/\\\/lamaletadelili.com\\\/ca\\\/tag\\\/bruno-munari\\\/\",\"name\":\"Bruno Munari archivos - La maleta de Lili\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lamaletadelili.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lamaletadelili.com\\\/ca\\\/tag\\\/bruno-munari\\\/#breadcrumb\"},\"inLanguage\":\"ca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lamaletadelili.com\\\/ca\\\/tag\\\/bruno-munari\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lamaletadelili.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bruno Munari\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lamaletadelili.com\\\/#website\",\"url\":\"https:\\\/\\\/lamaletadelili.com\\\/\",\"name\":\"La maleta de Lili\",\"description\":\"Cuenta cuentos\",\"publisher\":{\"@id\":\"https:\\\/\\\/lamaletadelili.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lamaletadelili.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lamaletadelili.com\\\/#organization\",\"name\":\"La maleta de Lili\",\"url\":\"https:\\\/\\\/lamaletadelili.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/lamaletadelili.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lamaletadelili.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/LOGO-La-maleta-de-Lili-catalan.png\",\"contentUrl\":\"https:\\\/\\\/lamaletadelili.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/LOGO-La-maleta-de-Lili-catalan.png\",\"width\":450,\"height\":177,\"caption\":\"La maleta de Lili\"},\"image\":{\"@id\":\"https:\\\/\\\/lamaletadelili.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bruno Munari archivos - La maleta de Lili","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lamaletadelili.com\/ca\/tag\/bruno-munari\/","og_locale":"ca_ES","og_type":"article","og_title":"Bruno Munari archivos - La maleta de Lili","og_url":"https:\/\/lamaletadelili.com\/ca\/tag\/bruno-munari\/","og_site_name":"La maleta de Lili","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lamaletadelili.com\/ca\/tag\/bruno-munari\/","url":"https:\/\/lamaletadelili.com\/ca\/tag\/bruno-munari\/","name":"Bruno Munari archivos - La maleta de Lili","isPartOf":{"@id":"https:\/\/lamaletadelili.com\/#website"},"breadcrumb":{"@id":"https:\/\/lamaletadelili.com\/ca\/tag\/bruno-munari\/#breadcrumb"},"inLanguage":"ca"},{"@type":"BreadcrumbList","@id":"https:\/\/lamaletadelili.com\/ca\/tag\/bruno-munari\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lamaletadelili.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Bruno Munari"}]},{"@type":"WebSite","@id":"https:\/\/lamaletadelili.com\/#website","url":"https:\/\/lamaletadelili.com\/","name":"La maleta de Lili","description":"Cuenta cuentos","publisher":{"@id":"https:\/\/lamaletadelili.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lamaletadelili.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/lamaletadelili.com\/#organization","name":"La maleta de Lili","url":"https:\/\/lamaletadelili.com\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/lamaletadelili.com\/#\/schema\/logo\/image\/","url":"https:\/\/lamaletadelili.com\/wp-content\/uploads\/2019\/07\/LOGO-La-maleta-de-Lili-catalan.png","contentUrl":"https:\/\/lamaletadelili.com\/wp-content\/uploads\/2019\/07\/LOGO-La-maleta-de-Lili-catalan.png","width":450,"height":177,"caption":"La maleta de Lili"},"image":{"@id":"https:\/\/lamaletadelili.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lamaletadelili.com\/ca\/wp-json\/wp\/v2\/tags\/822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lamaletadelili.com\/ca\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/lamaletadelili.com\/ca\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/lamaletadelili.com\/ca\/wp-json\/wp\/v2\/posts?tags=822"},{"href":"https:\/\/lamaletadelili.com\/ca\/wp-json\/wp\/v2\/tribe_events?tags=822"},{"href":"https:\/\/lamaletadelili.com\/ca\/wp-json\/wp\/v2\/tec_calendar_embed?tags=822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}